{"id":200,"count":2,"description":"<strong>Todos los ni\u00f1os merecen las mismas oportunidades fuera de la escuela. <\/strong>\r\n\r\nLos centros abiertos de C\u00e1ritas est\u00e1n pensados para familias que tienen ni\u00f1os y adolescentes de entre 6 y 18 a\u00f1os que requieren el apoyo y ayuda externa <strong>para ofrecer a sus hijos la oportunidad de recibir un acompa\u00f1amiento educativo, potenciando la adquisici\u00f3n de aprendizajes y competencias. <\/strong>\r\n\r\nEl servicio de centros abiertos de C\u00e1ritas <strong>es un servicio socio educativo que va dirigido a toda la unidad familiar, en tanto que es la familia el primer espacio de socializaci\u00f3n y de aprendizaje del ni\u00f1o.<\/strong> Por eso, lo que se ofrece no va dirigido solo a los ni\u00f1os que asisten, sino que <strong>busca fortalecer las relaciones familiares y potenciar las capacidades parentales. <\/strong>\r\n\r\nA diario, y en horario extraescolar, <strong>se llevan a cabo actividades formativas y l\u00fadicas que promueven las habilidades y el crecimiento emocional de los ni\u00f1os<\/strong> y procuran fortalecer las relaciones familiares. Se proponen diferentes actividades: la mayor\u00eda van dirigidas solo a los ni\u00f1os, pero otras son para toda la familia y\/o bien para los adultos. \r\n\r\nActualmente, hay dos centros en la ciudad de Barcelona: el <a href=\"\/\/es.caritas-suara-torrebaro-llops.org\/\">Centro Abierto Torre Bar\u00f3<\/a> (zona 3) y el <a href=\"\/\/es.caritas-suara-glamparetes.org\/\"> Centro Abierto Glamperetes en la Barceloneta<\/a> (zona 1). \r\n","link":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/","name":"Centros abiertos","slug":"centros-abiertos","taxonomy":"category","parent":197,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Todos los ni\u00f1os merecen las mismas oportunidades fuera de la escuela. Los centros abiertos de C\u00e1ritas est\u00e1n pensados para familias que tienen ni\u00f1os y adolescentes de entre 6 y 18 a\u00f1os que requieren el apoyo y ayuda externa para ofrecer a sus hijos la oportunidad de recibir un acompa\u00f1amiento educativo, potenciando la adquisici\u00f3n de aprendizajes y competencias. El servicio de centros abiertos de C\u00e1ritas es un servicio socio educativo que va dirigido a toda la unidad familiar, en tanto que es la familia el primer espacio de socializaci\u00f3n y de aprendizaje del ni\u00f1o. Por eso, lo que se ofrece no va dirigido solo a los ni\u00f1os que asisten, sino que busca fortalecer las relaciones familiares y potenciar las capacidades parentales. A diario, y en horario extraescolar, se llevan a cabo actividades formativas y l\u00fadicas que promueven las habilidades y el crecimiento emocional de los ni\u00f1os y procuran fortalecer las relaciones familiares. Se proponen diferentes actividades: la mayor\u00eda van dirigidas solo a los ni\u00f1os, pero otras son para toda la familia y\/o bien para los adultos. Actualmente, hay dos centros en la ciudad de Barcelona: el Centro Abierto Torre Bar\u00f3 (zona 3) y el Centro Abierto Glamperetes en la Barceloneta (zona 1).\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/#listItem\",\"name\":\"Familias e infancia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/#listItem\",\"position\":2,\"name\":\"Familias e infancia\",\"item\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/centros-abiertos\\\/#listItem\",\"name\":\"Centros abiertos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/centros-abiertos\\\/#listItem\",\"position\":3,\"name\":\"Centros abiertos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/familias-e-infancia\\\/#listItem\",\"name\":\"Familias e infancia\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/#collectionpage\",\"url\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/\",\"name\":\"Centros abiertos | Caritas Barcelona\",\"description\":\"Todos los ni\\u00f1os merecen las mismas oportunidades fuera de la escuela. Los centros abiertos de C\\u00e1ritas est\\u00e1n pensados para familias que tienen ni\\u00f1os y adolescentes de entre 6 y 18 a\\u00f1os que requieren el apoyo y ayuda externa para ofrecer a sus hijos la oportunidad de recibir un acompa\\u00f1amiento educativo, potenciando la adquisici\\u00f3n de aprendizajes y competencias. El servicio de centros abiertos de C\\u00e1ritas es un servicio socio educativo que va dirigido a toda la unidad familiar, en tanto que es la familia el primer espacio de socializaci\\u00f3n y de aprendizaje del ni\\u00f1o. Por eso, lo que se ofrece no va dirigido solo a los ni\\u00f1os que asisten, sino que busca fortalecer las relaciones familiares y potenciar las capacidades parentales. A diario, y en horario extraescolar, se llevan a cabo actividades formativas y l\\u00fadicas que promueven las habilidades y el crecimiento emocional de los ni\\u00f1os y procuran fortalecer las relaciones familiares. Se proponen diferentes actividades: la mayor\\u00eda van dirigidas solo a los ni\\u00f1os, pero otras son para toda la familia y\\\/o bien para los adultos. Actualmente, hay dos centros en la ciudad de Barcelona: el Centro Abierto Torre Bar\\u00f3 (zona 3) y el Centro Abierto Glamperetes en la Barceloneta (zona 1).\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#organization\",\"name\":\"Caritas Barcelona\",\"url\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/caritas.barcelona\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_CDB.jpg\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/#organizationLogo\",\"width\":900,\"height\":900,\"caption\":\"LOGO_CDB\"},\"image\":{\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/200\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/caritasbcn\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caritasbcn\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/c\\u00e0ritas-barcelona\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/\",\"name\":\"Caritas Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/caritas.barcelona\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Centros abiertos | Caritas Barcelona","description":"Todos los ni\u00f1os merecen las mismas oportunidades fuera de la escuela. Los centros abiertos de C\u00e1ritas est\u00e1n pensados para familias que tienen ni\u00f1os y adolescentes de entre 6 y 18 a\u00f1os que requieren el apoyo y ayuda externa para ofrecer a sus hijos la oportunidad de recibir un acompa\u00f1amiento educativo, potenciando la adquisici\u00f3n de aprendizajes y competencias. El servicio de centros abiertos de C\u00e1ritas es un servicio socio educativo que va dirigido a toda la unidad familiar, en tanto que es la familia el primer espacio de socializaci\u00f3n y de aprendizaje del ni\u00f1o. Por eso, lo que se ofrece no va dirigido solo a los ni\u00f1os que asisten, sino que busca fortalecer las relaciones familiares y potenciar las capacidades parentales. A diario, y en horario extraescolar, se llevan a cabo actividades formativas y l\u00fadicas que promueven las habilidades y el crecimiento emocional de los ni\u00f1os y procuran fortalecer las relaciones familiares. Se proponen diferentes actividades: la mayor\u00eda van dirigidas solo a los ni\u00f1os, pero otras son para toda la familia y\/o bien para los adultos. Actualmente, hay dos centros en la ciudad de Barcelona: el Centro Abierto Torre Bar\u00f3 (zona 3) y el Centro Abierto Glamperetes en la Barceloneta (zona 1).","canonical_url":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/caritas.barcelona\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/#listItem","name":"Familias e infancia"}},{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/#listItem","position":2,"name":"Familias e infancia","item":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/#listItem","name":"Centros abiertos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/#listItem","position":3,"name":"Centros abiertos","previousItem":{"@type":"ListItem","@id":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/#listItem","name":"Familias e infancia"}}]},{"@type":"CollectionPage","@id":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/#collectionpage","url":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/","name":"Centros abiertos | Caritas Barcelona","description":"Todos los ni\u00f1os merecen las mismas oportunidades fuera de la escuela. Los centros abiertos de C\u00e1ritas est\u00e1n pensados para familias que tienen ni\u00f1os y adolescentes de entre 6 y 18 a\u00f1os que requieren el apoyo y ayuda externa para ofrecer a sus hijos la oportunidad de recibir un acompa\u00f1amiento educativo, potenciando la adquisici\u00f3n de aprendizajes y competencias. El servicio de centros abiertos de C\u00e1ritas es un servicio socio educativo que va dirigido a toda la unidad familiar, en tanto que es la familia el primer espacio de socializaci\u00f3n y de aprendizaje del ni\u00f1o. Por eso, lo que se ofrece no va dirigido solo a los ni\u00f1os que asisten, sino que busca fortalecer las relaciones familiares y potenciar las capacidades parentales. A diario, y en horario extraescolar, se llevan a cabo actividades formativas y l\u00fadicas que promueven las habilidades y el crecimiento emocional de los ni\u00f1os y procuran fortalecer las relaciones familiares. Se proponen diferentes actividades: la mayor\u00eda van dirigidas solo a los ni\u00f1os, pero otras son para toda la familia y\/o bien para los adultos. Actualmente, hay dos centros en la ciudad de Barcelona: el Centro Abierto Torre Bar\u00f3 (zona 3) y el Centro Abierto Glamperetes en la Barceloneta (zona 1).","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/caritas.barcelona\/es\/#website"},"breadcrumb":{"@id":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/caritas.barcelona\/es\/#organization","name":"Caritas Barcelona","url":"https:\/\/caritas.barcelona\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/caritas.barcelona\/wp-content\/uploads\/2020\/03\/LOGO_CDB.jpg","@id":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/#organizationLogo","width":900,"height":900,"caption":"LOGO_CDB"},"image":{"@id":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/caritasbcn\/","https:\/\/www.youtube.com\/user\/caritasbcn","https:\/\/www.linkedin.com\/company\/c\u00e0ritas-barcelona"]},{"@type":"WebSite","@id":"https:\/\/caritas.barcelona\/es\/#website","url":"https:\/\/caritas.barcelona\/es\/","name":"Caritas Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/caritas.barcelona\/es\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/caritas.barcelona\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/\" title=\"Familias e infancia\">Familias e infancia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCentros abiertos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/caritas.barcelona\/es\/"},{"label":"Familias e infancia","link":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/"},{"label":"Centros abiertos","link":"https:\/\/caritas.barcelona\/es\/familias-e-infancia\/centros-abiertos\/"}],"_links":{"self":[{"href":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/categories\/197"}],"wp:post_type":[{"href":"https:\/\/caritas.barcelona\/es\/wp-json\/wp\/v2\/posts?categories=200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}